{"id":11195,"date":"2024-06-18T20:29:32","date_gmt":"2024-06-18T20:29:32","guid":{"rendered":"https:\/\/brizyproducts.com\/how-to-order-2\/"},"modified":"2026-03-20T14:45:22","modified_gmt":"2026-03-20T14:45:22","slug":"how-to-order","status":"publish","type":"page","link":"https:\/\/brizyproducts.com\/fr\/how-to-order\/","title":{"rendered":"Comment commander"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull has-custom-content-position is-position-bottom-left\" style=\"padding-top:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);min-height:83vh;aspect-ratio:unset;\"><img decoding=\"async\" width=\"2560\" height=\"1709\" sizes=\"100vw\" class=\"wp-block-cover__image-background wp-image-4387\" alt=\"\" src=\"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-scaled.webp\" data-object-fit=\"cover\" srcset=\"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-scaled.webp 2560w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-900x601.webp 900w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-300x200.webp 300w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-768x513.webp 768w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-1536x1025.webp 1536w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-2048x1367.webp 2048w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-600x401.webp 600w\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-skogsgron-background-color has-background-dim-20 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-container-core-cover-is-layout-1ead8876 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-c84a538d wp-block-group-is-layout-constrained\">\n<h1 class=\"wp-block-heading has-vinter-color has-text-color has-link-color has-heading-1-font-size wp-elements-2a054aca6d570f7fb9888291e96e8be2\">Comment commander<\/h1>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-9058238a wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--40)\">\n<h2 class=\"wp-block-heading has-text-align-center\">Comment commander des produits sur mesure chez Brizy?<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Notre mission est de cr\u00e9er des v\u00eatements sur mesure qui r\u00e9pondent \u00e0 vos besoins sp\u00e9cifiques. Nous prenons en charge le processus du d\u00e9but \u00e0 la fin, des mesures initiales \u00e0 la livraison du produit fini.<br><br>Si vous avez des questions ou des doutes, n\u2019h\u00e9sitez pas \u00e0 nous contacter.<br><mark style=\"background-color:rgba(0, 0, 0, 0);color:#B02936\" class=\"has-inline-color\"><a href=\"mailto:info@brizy.se\">info@brizy.se<\/a><\/mark> ou +46 320-161 95<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-c3d5205c wp-block-buttons-is-layout-flex\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/?page_id=16047\" target=\"_blank\" rel=\"noreferrer noopener\">Formulaire de commande<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group step-line has-global-padding is-layout-constrained wp-container-core-group-is-layout-ef10769c wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60);padding-top:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--60)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-96cfbf2b wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:550px\">\n<h3 class=\"wp-block-heading\">1. <strong><strong>Pr\u00e9paration<\/strong><\/strong><\/h3>\n\n\n\n<p>Remplissez notre formulaire de commande en indiquant vos mesures et vos sp\u00e9cifications. Vous pouvez consulter notre vid\u00e9o explicative afin de prendre vos mesures correctement. Une fois vos informations re\u00e7ues, nous vous contacterons en cas de questions afin de v\u00e9rifier que tout est correct.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-96cfbf2b wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:550px\">\n<h3 class=\"wp-block-heading\">2. <strong>Confirmation de la commande<\/strong><\/h3>\n\n\n\n<p><strong> <\/strong>Une fois que vous \u00eates satisfait des d\u00e9tails de la commande, vous payez la commande avant de passer \u00e0 l&rsquo;\u00e9tape suivante.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-96cfbf2b wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:550px\">\n<h3 class=\"wp-block-heading\">3. <strong>Conception et retour d&rsquo;information<\/strong><\/h3>\n\n\n\n<p>Nous cr\u00e9ons les dessins et les mod\u00e8les sur la base de vos commentaires. Si vous n&rsquo;\u00eates pas satisfait, nous apportons les modifications n\u00e9cessaires. Vous donnez votre approbation finale avant que nous ne proc\u00e9dions \u00e0 la production.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-96cfbf2b wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:550px\">\n<h3 class=\"wp-block-heading\">4. Produktion<\/h3>\n\n\n\n<p>Le processus de production commence et dure g\u00e9n\u00e9ralement 4 semaines. Une fois que les produits sont pr\u00eats, nous vous les envoyons directement. L&rsquo;exp\u00e9dition prend g\u00e9n\u00e9ralement une semaine.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-96cfbf2b wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:550px\">\n<h3 class=\"wp-block-heading\">5. <strong>Douanes et taxes<\/strong><\/h3>\n\n\n\n<p><strong> <\/strong>Si vous \u00eates situ\u00e9 en dehors de l&rsquo;UE et que nous avons effectu\u00e9 une livraison DDP (Delivered Duty Paid), vous devrez payer les droits de douane et les taxes \u00e0 la r\u00e9ception des marchandises.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-96cfbf2b wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:550px\">\n<h3 class=\"wp-block-heading\">6. <strong>Garantie de satisfaction<\/strong><\/h3>\n\n\n\n<p><strong> <\/strong>Si vous n&rsquo;\u00eates pas satisfait du produit final, veuillez nous contacter imm\u00e9diatement afin que nous puissions r\u00e9pondre \u00e0 vos pr\u00e9occupations.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"padding-top:var(--wp--preset--spacing--40)\">Instructions de mesure<\/h2>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 1280 \/ 720;\" width=\"1280\" autoplay controls muted src=\"https:\/\/brizyproducts.com\/wp-content\/uploads\/2024\/04\/brizy_mesurements.mp4\"><\/video><\/figure>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-f3d41a57 wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--70);margin-bottom:var(--wp--preset--spacing--70);padding-top:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--40)\">\n<p class=\"has-text-align-center has-midnatt-color has-text-color has-link-color has-body-lg-font-size wp-elements-dbcd35993b4d6bdf046ed82e48bfb630\">Chez Brizy, nous nous engageons \u00e0 vous fournir des v\u00eatements de haute qualit\u00e9, sur mesure, qui vous vont parfaitement et r\u00e9pondent \u00e0 vos attentes. N&rsquo;h\u00e9sitez pas \u00e0 nous contacter pour plus d&rsquo;informations ou pour commencer votre commande d\u00e8s aujourd&rsquo;hui.<\/p>\n<\/div>\n\n\n\n<style>.step-line {\n  position: relative;\n}\n\n@media (min-width: 1100px) {\n  .step-line::before {\n    content: '';\n    position: absolute;\n    top: 0;\n    bottom: 0;\n    left: 50%;\n    width: 1px; \/* Adjust thickness *\/\n    background: rgba(0, 0, 0, 0.1); \/* Adjust transparency and color *\/\n    transform: translateX(-50%);\n    pointer-events: none; \/* Makes sure it doesn't interfere with clicks *\/\n  }\n}<\/style>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-container-core-group-is-layout-4cc4d920 wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\" style=\"margin-top:var(--wp--preset--spacing--70);margin-bottom:var(--wp--preset--spacing--70)\"><img data-dominant-color=\"4f4140\" data-has-transparency=\"true\" style=\"--dominant-color: #4f4140;\" decoding=\"async\" width=\"1800\" height=\"1243\" sizes=\"(max-width: clamp(300px, 100%, 3150px)) 100vw, clamp(300px, 100%, 3150px)\" src=\"https:\/\/brizyproducts.com\/wp-content\/uploads\/2025\/01\/tm-media-rev.png-edit-png-1.webp\" alt=\"\" class=\"wp-image-15029 has-transparency\" srcset=\"https:\/\/brizyproducts.com\/wp-content\/uploads\/2025\/01\/tm-media-rev.png-edit-png-1.webp 1800w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2025\/01\/tm-media-rev.png-edit-png-1-900x622.webp 900w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2025\/01\/tm-media-rev.png-edit-png-1-300x207.webp 300w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2025\/01\/tm-media-rev.png-edit-png-1-768x530.webp 768w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2025\/01\/tm-media-rev.png-edit-png-1-1536x1061.webp 1536w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2025\/01\/tm-media-rev.png-edit-png-1-600x414.webp 600w\" \/><\/figure>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"padding-top:var(--wp--preset--spacing--40)\">Carte en couleur<\/h2>\n\n\n\n<div class=\"card-columns colormap row\">\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ffffff; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#22 White<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#000005; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#1 Black<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#3f5851; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#2 Dark Green<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#3c9a4f; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#5 Kelly Green<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#2b8035; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#3 Light Green<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#3b7068; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#4 Green<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#7dea2f; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#64 Green 368c<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#156352; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#59 Green JD<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#b5b300; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#63 Green 457c<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#367860; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#60 Green TU<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#a5b700; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#61 Green 5912<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#13ba81; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#33 Pastel Green<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#769abd; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#51 Blue MT<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#41639c; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#29 Royal Blue<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#004190; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#34 Dark Blue<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#4ed1f2; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#53 Blue 298c<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#addbf4; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#6 Light Blue<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#4386d7; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#7 Blue<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#3b4157; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#9 Navy Blue<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#a23457; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#13 Winered<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#800524; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#14 US Burgundy<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#e50022; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#15 Red<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ff7542; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#16 Orange<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#c30f43; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#50 Red MT<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#cb2430; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#55 Red 187c<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#bc132e; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#54 Red AM<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ee1216; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#56 Red 186c<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ff5228; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#25 US Orange<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ad283a; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#38 Maroon Red<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ee1216; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#57 Red 185c<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#726a65; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#20 Dark Grey<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#b7bbbf; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#21 Light Grey<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#85888b; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#37 Silver<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#7d7e7f; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#23 Grey<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#726a65; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#52 US Grey &#8211; 425c<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#00aaad; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#27 Turquoise<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#0090c3; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#28 US Turquoise<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#540076; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#65 Purple DN<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#7c3b75; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#31 Dark Purple<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#974ce7; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#10 Purple<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#cb4267; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#12 Cerise<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#7a43d2; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#67 Purple 2090u<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#c88ddb; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#68 Purple 2577u<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#fd1c98; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#69 Cerise112<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#92009a; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#66 Purple 110<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ffbdc3; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#11 Pink<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#edd9c0; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#32 Beige<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ffd37b; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#71 Yellow 141u<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ffdb00; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#58 Yellow RB<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ffff00; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#27 US Yellow<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ffc420; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#17 Yellow<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#f6d193; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#72 Yellow 7508<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#ffbc38; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#49 Yellow 1375<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#a88254; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#70 Dark Gold 871c<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#cfa836; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#8 Goop Gold<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#765f4c; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#73 Brown AH<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#d09914; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#36 Gold<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#d0992c; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#30 Tobacco<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#835a49; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#18 Brown<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n        <div class=\"col-6 col-sm-4 col-md-3\">\n        <div class=\"card\">\n          <div class=\"card-header text-light\" style=\"background-color:#694B30; \"><\/div>\n              <div class=\"card-body\">\n              <h5 class=\"card-title\">#19 Dark Brown<\/h5>\n            <\/div>\n          <\/div>\n      <\/div>\n\n  \n<\/div>\n\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light\"><img decoding=\"async\" width=\"2560\" height=\"1709\" sizes=\"100vw\" class=\"wp-block-cover__image-background wp-image-4386\" alt=\"\" src=\"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4053-scaled.webp\" data-object-fit=\"cover\" srcset=\"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4053-scaled.webp 2560w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4053-900x601.webp 900w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4053-300x200.webp 300w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4053-768x513.webp 768w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4053-1536x1025.webp 1536w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4053-2048x1367.webp 2048w, https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4053-600x401.webp 600w\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-fjalltopp-background-color has-background-dim-70 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h3 class=\"wp-block-heading has-text-align-center has-vinter-color has-text-color has-link-color wp-elements-c6b871ae199329c9ec1e7662ab99e26c\" style=\"line-height:1.2\">V\u00eatements personnalis\u00e9s pour<br>Harness Racing et Stable<\/h3>\n\n\n\n<p class=\"has-text-align-center\">D\u00e9couvrez nos produits sur mesure<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\">Aller aux produits<\/a><\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Comment commander des produits sur mesure chez Brizy? Notre mission est de cr\u00e9er des v\u00eatements sur mesure qui r\u00e9pondent \u00e0 vos besoins sp\u00e9cifiques. Nous prenons en charge le processus du d\u00e9but \u00e0 la fin, des mesures initiales \u00e0 la livraison du produit fini. Si vous avez des questions ou des doutes, n\u2019h\u00e9sitez pas \u00e0 nous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11383,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"how-to-order","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11195","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment commander | Brizy<\/title>\n<meta name=\"description\" content=\"Comment commander Comment commander des produits sur mesure chez Brizy? Notre mission est de cr\u00e9er des v\u00eatements sur mesure qui r\u00e9pondent \u00e0 vos besoins\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brizyproducts.com\/fr\/how-to-order\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment commander | Brizy\" \/>\n<meta property=\"og:description\" content=\"Comment commander Comment commander des produits sur mesure chez Brizy? Notre mission est de cr\u00e9er des v\u00eatements sur mesure qui r\u00e9pondent \u00e0 vos besoins\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brizyproducts.com\/fr\/how-to-order\/\" \/>\n<meta property=\"og:site_name\" content=\"Brizy Products\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/brizy.1983\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T14:45:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment commander | Brizy","description":"Comment commander Comment commander des produits sur mesure chez Brizy? Notre mission est de cr\u00e9er des v\u00eatements sur mesure qui r\u00e9pondent \u00e0 vos besoins","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brizyproducts.com\/fr\/how-to-order\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment commander | Brizy","og_description":"Comment commander Comment commander des produits sur mesure chez Brizy? Notre mission est de cr\u00e9er des v\u00eatements sur mesure qui r\u00e9pondent \u00e0 vos besoins","og_url":"https:\/\/brizyproducts.com\/fr\/how-to-order\/","og_site_name":"Brizy Products","article_publisher":"https:\/\/www.facebook.com\/brizy.1983\/","article_modified_time":"2026-03-20T14:45:22+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-scaled.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brizyproducts.com\/fr\/how-to-order\/","url":"https:\/\/brizyproducts.com\/fr\/how-to-order\/","name":"Comment commander | Brizy","isPartOf":{"@id":"https:\/\/brizyproducts.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brizyproducts.com\/fr\/how-to-order\/#primaryimage"},"image":{"@id":"https:\/\/brizyproducts.com\/fr\/how-to-order\/#primaryimage"},"thumbnailUrl":"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-scaled.webp","datePublished":"2024-06-18T20:29:32+00:00","dateModified":"2026-03-20T14:45:22+00:00","description":"Comment commander Comment commander des produits sur mesure chez Brizy? Notre mission est de cr\u00e9er des v\u00eatements sur mesure qui r\u00e9pondent \u00e0 vos besoins","breadcrumb":{"@id":"https:\/\/brizyproducts.com\/fr\/how-to-order\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brizyproducts.com\/fr\/how-to-order\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/brizyproducts.com\/fr\/how-to-order\/#primaryimage","url":"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-scaled.webp","contentUrl":"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/11\/DSC_4050-scaled.webp","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/brizyproducts.com\/fr\/how-to-order\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/brizyproducts.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment commander"}]},{"@type":"WebSite","@id":"https:\/\/brizyproducts.com\/fr\/#website","url":"https:\/\/brizyproducts.com\/fr\/","name":"Brizy","description":"","publisher":{"@id":"https:\/\/brizyproducts.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brizyproducts.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/brizyproducts.com\/fr\/#organization","name":"Brizy","url":"https:\/\/brizyproducts.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/brizyproducts.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/12\/Brizy-old.svg","contentUrl":"https:\/\/brizyproducts.com\/wp-content\/uploads\/2023\/12\/Brizy-old.svg","width":1,"height":1,"caption":"Brizy"},"image":{"@id":"https:\/\/brizyproducts.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/brizy.1983\/","https:\/\/www.linkedin.com\/company\/brizy-produktion\/"]}]}},"_links":{"self":[{"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/pages\/11195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/comments?post=11195"}],"version-history":[{"count":2,"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/pages\/11195\/revisions"}],"predecessor-version":[{"id":23268,"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/pages\/11195\/revisions\/23268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/media\/11383"}],"wp:attachment":[{"href":"https:\/\/brizyproducts.com\/fr\/wp-json\/wp\/v2\/media?parent=11195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}